{"id":1682,"date":"2020-06-15T13:30:23","date_gmt":"2020-06-15T11:30:23","guid":{"rendered":"https:\/\/www.abeillenoire.eu\/cms\/?p=1682"},"modified":"2020-11-26T09:39:04","modified_gmt":"2020-11-26T08:39:04","slug":"la-bourdaine","status":"publish","type":"post","link":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/","title":{"rendered":"La bourdaine"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]L\u2019arbuste est si discret qu\u2019il reste souvent m\u00e9connu. Il fr\u00e9quente les lisi\u00e8res, les sous-bois clairs un peu humides. Une fois qu\u2019on a rep\u00e9r\u00e9 la bourdaine on en voit partout. Ses fleurs blanches, \u00e0 peine ros\u00e9es, tout \u00e0 fait discr\u00e8tes apparaissent d\u00e8s le d\u00e9but mai. Elles pr\u00e9c\u00e8dent la floraison de l\u2019acacia. Les abeilles noires les visitent de fa\u00e7on tr\u00e8s assidue. Elles durent g\u00e9n\u00e9ralement jusqu\u2019\u00e0 la fin juin, mais s\u2019il pleut, la floraison se prolonge en Juillet et elles cohabitent avec des baies globuleuses d\u2019abord vertes, puis rouge\u00e2tres et enfin noires. Pour voir les fleurs qui ne font gu\u00e8re plus d\u20191mm, il faut de bons yeux. Ce sont le plus souvent les abeilles qui les signalent.<\/p>\n<p>Pour reconnaitre la bourdaine il vaut mieux se fier aux feuilles, lisses, nervur\u00e9es et brillantes comme celles d\u2019un h\u00eatre, \u00e0 son \u00e9corce brune constell\u00e9e de points clairs. Le bois frais, sous l\u2019\u00e9corce est d\u2019une couleur orange qui ne trompe pas.<\/p>\n<p>Toute la plante est toxique, mais le miel est fruit\u00e9 avec un go\u00fbt raffin\u00e9 proche du caramel et il est parfaitement comestible. En Sologne, la bourdaine teinte et parfume volontiers la miell\u00e9e d\u2019acacia.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]L\u2019arbuste est si discret qu\u2019il reste souvent m\u00e9connu. Il fr\u00e9quente les lisi\u00e8res, les sous-bois clairs un peu humides. Une fois qu\u2019on a rep\u00e9r\u00e9 la bourdaine on en voit partout. Ses&hellip;<\/p>\n","protected":false},"author":5,"featured_media":1691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conservatoire-abeille-noire","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La bourdaine - Conservatoire de l&#039;Abeille Noire<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La bourdaine - Conservatoire de l&#039;Abeille Noire\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]L\u2019arbuste est si discret qu\u2019il reste souvent m\u00e9connu. Il fr\u00e9quente les lisi\u00e8res, les sous-bois clairs un peu humides. Une fois qu\u2019on a rep\u00e9r\u00e9 la bourdaine on en voit partout. Ses&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Conservatoire de l&#039;Abeille Noire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANSOLOGNE\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-15T11:30:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-26T08:39:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"abeillenoire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"abeillenoire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/\"},\"author\":{\"name\":\"abeillenoire\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#\\\/schema\\\/person\\\/595739578f5150cd847d05c76677e64c\"},\"headline\":\"La bourdaine\",\"datePublished\":\"2020-06-15T11:30:23+00:00\",\"dateModified\":\"2020-11-26T08:39:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bourdaine2498-scaled.jpg\",\"articleSection\":[\"Conservatoire de l'abeille noire\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/\",\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/\",\"name\":\"La bourdaine - Conservatoire de l&#039;Abeille Noire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bourdaine2498-scaled.jpg\",\"datePublished\":\"2020-06-15T11:30:23+00:00\",\"dateModified\":\"2020-11-26T08:39:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bourdaine2498-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/bourdaine2498-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/la-bourdaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La bourdaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/\",\"name\":\"Conservatoire de l&#039;Abeille Noire\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#organization\",\"name\":\"Conservatoire de l'Abeille Noire en Val de Loire - Sologne - For\u00eat\",\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-conservatoire-abeille-noire.jpg\",\"contentUrl\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/logo-conservatoire-abeille-noire.jpg\",\"width\":189,\"height\":88,\"caption\":\"Conservatoire de l'Abeille Noire en Val de Loire - Sologne - For\u00eat\"},\"image\":{\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANSOLOGNE\",\"https:\\\/\\\/www.instagram.com\\\/conservatoire_abeille_noire\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/#\\\/schema\\\/person\\\/595739578f5150cd847d05c76677e64c\",\"name\":\"abeillenoire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g\",\"caption\":\"abeillenoire\"},\"url\":\"https:\\\/\\\/www.abeillenoire.eu\\\/cms\\\/author\\\/abeillenoire\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La bourdaine - Conservatoire de l&#039;Abeille Noire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/","og_locale":"fr_FR","og_type":"article","og_title":"La bourdaine - Conservatoire de l&#039;Abeille Noire","og_description":"[vc_row][vc_column][vc_column_text]L\u2019arbuste est si discret qu\u2019il reste souvent m\u00e9connu. Il fr\u00e9quente les lisi\u00e8res, les sous-bois clairs un peu humides. Une fois qu\u2019on a rep\u00e9r\u00e9 la bourdaine on en voit partout. Ses&hellip;","og_url":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/","og_site_name":"Conservatoire de l&#039;Abeille Noire","article_publisher":"https:\/\/www.facebook.com\/CANSOLOGNE","article_published_time":"2020-06-15T11:30:23+00:00","article_modified_time":"2020-11-26T08:39:04+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg","type":"image\/jpeg"}],"author":"abeillenoire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"abeillenoire","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#article","isPartOf":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/"},"author":{"name":"abeillenoire","@id":"https:\/\/www.abeillenoire.eu\/cms\/#\/schema\/person\/595739578f5150cd847d05c76677e64c"},"headline":"La bourdaine","datePublished":"2020-06-15T11:30:23+00:00","dateModified":"2020-11-26T08:39:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/"},"wordCount":232,"publisher":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/#organization"},"image":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg","articleSection":["Conservatoire de l'abeille noire"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/","url":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/","name":"La bourdaine - Conservatoire de l&#039;Abeille Noire","isPartOf":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#primaryimage"},"image":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg","datePublished":"2020-06-15T11:30:23+00:00","dateModified":"2020-11-26T08:39:04+00:00","breadcrumb":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#primaryimage","url":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg","contentUrl":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/bourdaine2498-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/www.abeillenoire.eu\/cms\/la-bourdaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.abeillenoire.eu\/cms\/"},{"@type":"ListItem","position":2,"name":"La bourdaine"}]},{"@type":"WebSite","@id":"https:\/\/www.abeillenoire.eu\/cms\/#website","url":"https:\/\/www.abeillenoire.eu\/cms\/","name":"Conservatoire de l&#039;Abeille Noire","description":"","publisher":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abeillenoire.eu\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.abeillenoire.eu\/cms\/#organization","name":"Conservatoire de l'Abeille Noire en Val de Loire - Sologne - For\u00eat","url":"https:\/\/www.abeillenoire.eu\/cms\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.abeillenoire.eu\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/logo-conservatoire-abeille-noire.jpg","contentUrl":"https:\/\/www.abeillenoire.eu\/cms\/wp-content\/uploads\/2020\/06\/logo-conservatoire-abeille-noire.jpg","width":189,"height":88,"caption":"Conservatoire de l'Abeille Noire en Val de Loire - Sologne - For\u00eat"},"image":{"@id":"https:\/\/www.abeillenoire.eu\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANSOLOGNE","https:\/\/www.instagram.com\/conservatoire_abeille_noire\/"]},{"@type":"Person","@id":"https:\/\/www.abeillenoire.eu\/cms\/#\/schema\/person\/595739578f5150cd847d05c76677e64c","name":"abeillenoire","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9253310a33f9649ec364f0afefbaa584d26c8df46a81e2777435f59ad4f5916?s=96&d=blank&r=g","caption":"abeillenoire"},"url":"https:\/\/www.abeillenoire.eu\/cms\/author\/abeillenoire\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/posts\/1682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/comments?post=1682"}],"version-history":[{"count":3,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/posts\/1682\/revisions"}],"predecessor-version":[{"id":1692,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/posts\/1682\/revisions\/1692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/media\/1691"}],"wp:attachment":[{"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/media?parent=1682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/categories?post=1682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abeillenoire.eu\/cms\/wp-json\/wp\/v2\/tags?post=1682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}